{"id":2275,"date":"2018-09-13T10:51:09","date_gmt":"2018-09-13T09:51:09","guid":{"rendered":"http:\/\/jpa67.fr\/fr\/?p=2275"},"modified":"2018-09-24T11:47:52","modified_gmt":"2018-09-24T10:47:52","slug":"reunion-dinformations-2","status":"publish","type":"post","link":"https:\/\/jpa67.fr\/fr\/reunion-dinformations-2\/","title":{"rendered":"R\u00e9union d&rsquo;informations"},"content":{"rendered":"<header class=\"entry-header\">\n<h1 class=\"entry-title\">R\u00e9union d\u2019informations \u2013 19 octobre 2018<\/h1>\n<\/header>\n<div class=\"entry-content\">\n<h1><strong>UN PROJET \u00ab\u00a0LOISIRS\u00a0\u00bb ?<\/strong><\/h1>\n<p>Le Centre Ressources Enfance-Jeunesse &amp; Handicap (CREJH)\u00a0de la Jeunesse au Plein Air (JPA) du Bas-Rhin peut vous apporter des informations et des conseils pour un accueil en centre de loisirs, un d\u00e9part en colonie de vacances, besoin d\u2019un temps de r\u00e9pit, etc\u2026<\/p>\n<p>Nous vous proposons de nous rencontrer le<\/p>\n<p><strong>Vendredi 19 octobre 2018 \u00e0 9h\u00a0<\/strong><\/p>\n<p>dans les locaux de la Ligue de l\u2019enseignement<\/p>\n<p>15 rue de l\u2019Industrie 67400 Illkirch<\/p>\n<p><strong>Au programme de cette matin\u00e9e :<\/strong><\/p>\n<p>Pr\u00e9sentation :<\/p>\n<ul>\n<li><strong>Du Centre Ressources Enfance-Jeunesse &amp; Handicap de la JPA67<\/strong><br \/>\n<u>Mission<\/u>\u00a0: Faciliter l\u2019accueil des enfants en situation de handicap dans les structures de loisirs (P\u00e9riscolaire, centre de loisirs, Colonie de vacances, etc\u2026)<br \/>\n<a href=\"http:\/\/jpa67.fr\/fr\/nos-actions\/espace-ressources-loisirs-et-handicap\/\">http:\/\/jpa67.fr\/fr\/nos-actions\/espace-ressources-loisirs-et-handicap\/<\/a><\/li>\n<li><b>Des diff\u00e9rentes aides li\u00e9es au handicap ( AEEH, PCH, &#8230; )<\/b><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Pour nous permettre de vous accueillir dans les meilleures conditions, nous vous prions de bien vouloir nous informer de votre pr\u00e9sence par retour de mail (<a href=\"mailto:loisirs.handicap@jpa67.fr\">loisirs.handicap@jpa67.fr<\/a>) ou avec <a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSew_2SFd1A6mUqHGWX8Ye1Yu6CiUQA53kxTrd9TdPXb799KUA\/viewform\">notre formulaire en ligne<\/a><\/strong><\/p>\n<p><strong><u>Pour plus de renseignement<\/u>\u00a0: 03 88 65 46 40<\/strong><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9union d\u2019informations \u2013 19 octobre 2018 UN PROJET \u00ab\u00a0LOISIRS\u00a0\u00bb ? Le Centre Ressources Enfance-Jeunesse &amp; Handicap (CREJH)\u00a0de la Jeunesse au [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1634,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[119,27],"tags":[],"jetpack_featured_media_url":"https:\/\/jpa67.fr\/fr\/wp-content\/uploads\/2018\/07\/affiche_reuInfos_sept.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7mWfa-AH","jetpack-related-posts":[{"id":2327,"url":"https:\/\/jpa67.fr\/fr\/reunion-dinformations-3\/","url_meta":{"origin":2275,"position":0},"title":"R\u00e9union d\u2019informations","date":"17 janvier 2019","format":false,"excerpt":"R\u00e9union d\u2019informations \u2013 22 f\u00e9vrier 2019 L\u2019accompagnement des services d\u2019aide \u00e0 la personne dans les loisirs Le Centre Ressources Enfance-Jeunesse & Handicap (CREJH)\u00a0de la Jeunesse au Plein Air (JPA) du Bas-Rhin peut vous apporter des informations et des conseils pour un accueil en centre de loisirs, un d\u00e9part en colonie\u2026","rel":"","context":"Dans &quot;Centre Ressources Enfance-Jeunesse &amp; Handicap&quot;","img":{"alt_text":"affiche_reuInfos_fev2019","src":"https:\/\/i0.wp.com\/jpa67.fr\/fr\/wp-content\/uploads\/2019\/01\/affiche_reuInfos_fev2019.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1315,"url":"https:\/\/jpa67.fr\/fr\/reunion-dinformations-18-mai-2018\/","url_meta":{"origin":2275,"position":1},"title":"R\u00e9union d&rsquo;informations &#8211; 18 mai 2018","date":"5 avril 2018","format":false,"excerpt":"UN PROJET \"LOISIRS\" ? Le Centre Ressources Enfance-Jeunesse & Handicap (CREJH)\u00a0de la Jeunesse au Plein Air (JPA) du Bas-Rhin peut vous apporter des informations et des conseils pour un accueil en centre de loisirs, un d\u00e9part en colonie de vacances, besoin d'un temps de r\u00e9pit, etc... Nous vous proposons de\u2026","rel":"","context":"Dans &quot;Centre Ressources Enfance-Jeunesse &amp; Handicap&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/jpa67.fr\/fr\/wp-content\/uploads\/2018\/03\/miseEnAvant_Wordpress.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1074,"url":"https:\/\/jpa67.fr\/fr\/reunion-dinformations\/","url_meta":{"origin":2275,"position":2},"title":"R\u00e9union d&rsquo;informations","date":"24 janvier 2018","format":false,"excerpt":"UN PROJET \"LOISIRS\" ? Le Centre Ressources Enfance-Jeunesse & Handicap (CREJH)\u00a0de la Jeunesse au Plein Air (JPA) du Bas-Rhin peut vous apporter des informations et des conseils pour un accueil en centre de loisirs, un d\u00e9part en colonie de vacances, besoin d'un temps de r\u00e9pit, etc... Nous vous proposons de\u2026","rel":"","context":"Dans &quot;Centre Ressources Enfance-Jeunesse &amp; Handicap&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/jpa67.fr\/fr\/wp-content\/uploads\/2018\/01\/banniereCREJH_Final_vecto.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1270,"url":"https:\/\/jpa67.fr\/fr\/reunion-dinformations-9-mars-2018\/","url_meta":{"origin":2275,"position":3},"title":"R\u00e9union d&rsquo;informations &#8211; 9 mars 2018","date":"5 mars 2018","format":false,"excerpt":"UN PROJET \"LOISIRS\" ? Le Centre Ressources Enfance-Jeunesse & Handicap (CREJH)\u00a0de la Jeunesse au Plein Air (JPA) du Bas-Rhin peut vous apporter des informations et des conseils pour un accueil en centre de loisirs, un d\u00e9part en colonie de vacances, besoin d'un temps de r\u00e9pit, etc... Nous vous proposons de\u2026","rel":"","context":"Dans &quot;archives&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/jpa67.fr\/fr\/wp-content\/uploads\/2018\/03\/miseEnAvant_Wordpress.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2424,"url":"https:\/\/jpa67.fr\/fr\/reunion-dinformations-novembre-2019\/","url_meta":{"origin":2275,"position":4},"title":"R\u00e9union d&rsquo;informations &#8211; Novembre 2019","date":"16 octobre 2019","format":false,"excerpt":"R\u00e9union d\u2019informations \u2013 8 novembre 2019 Accueil en P\u00e9riscolaire (Midi\u2014Soir), en Centre de Loisirs, en Colonie de Vacances ou pr\u00e9parer un s\u00e9jour \u00ab\u00a0Famille\u00a0\u00bb Le Centre Ressources Enfance-Jeunesse & Handicap (CREJH)\u00a0de la Jeunesse au Plein Air (JPA) du Bas-Rhin peut vous apporter des informations et des conseils pour un accueil en\u2026","rel":"","context":"Dans &quot;Centre Ressources Enfance-Jeunesse &amp; Handicap&quot;","img":{"alt_text":"Affiche r\u00e9union d'infos 8 novembre 2019","src":"https:\/\/i0.wp.com\/jpa67.fr\/fr\/wp-content\/uploads\/2019\/10\/REUNION-INFO-8-NOVEMBRE-2019.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2364,"url":"https:\/\/jpa67.fr\/fr\/2364-2\/","url_meta":{"origin":2275,"position":5},"title":"R\u00e9union d\u2019informations","date":"26 mars 2019","format":false,"excerpt":"R\u00e9union d\u2019informations \u2013 10 avril 2019 UN PROJET \u00ab\u00a0LOISIRS\u00a0\u00bb ? Le Centre Ressources Enfance-Jeunesse & Handicap (CREJH)\u00a0de la Jeunesse au Plein Air (JPA) du Bas-Rhin peut vous apporter des informations et des conseils pour un accueil en centre de loisirs, un d\u00e9part en colonie de vacances, besoin d\u2019un temps de\u2026","rel":"","context":"Dans &quot;Centre Ressources Enfance-Jeunesse &amp; Handicap&quot;","img":{"alt_text":"Affiche r\u00e9union","src":"https:\/\/i0.wp.com\/jpa67.fr\/fr\/wp-content\/uploads\/2019\/03\/affiche_reuInfos_modifiable.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/jpa67.fr\/fr\/wp-json\/wp\/v2\/posts\/2275"}],"collection":[{"href":"https:\/\/jpa67.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jpa67.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jpa67.fr\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jpa67.fr\/fr\/wp-json\/wp\/v2\/comments?post=2275"}],"version-history":[{"count":3,"href":"https:\/\/jpa67.fr\/fr\/wp-json\/wp\/v2\/posts\/2275\/revisions"}],"predecessor-version":[{"id":2297,"href":"https:\/\/jpa67.fr\/fr\/wp-json\/wp\/v2\/posts\/2275\/revisions\/2297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jpa67.fr\/fr\/wp-json\/wp\/v2\/media\/1634"}],"wp:attachment":[{"href":"https:\/\/jpa67.fr\/fr\/wp-json\/wp\/v2\/media?parent=2275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jpa67.fr\/fr\/wp-json\/wp\/v2\/categories?post=2275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jpa67.fr\/fr\/wp-json\/wp\/v2\/tags?post=2275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}